{"id":1438,"date":"2026-01-13T17:08:45","date_gmt":"2026-01-13T16:08:45","guid":{"rendered":"https:\/\/www.ecrivaine-essayiste.fr\/?p=1438"},"modified":"2026-01-13T17:08:48","modified_gmt":"2026-01-13T16:08:48","slug":"blizzard-et-les-ames-feroces-marie-vingtras","status":"publish","type":"post","link":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/","title":{"rendered":"BLIZZARD et LES \u00c2MES F\u00c9ROCES &#8211; Marie Vingtras"},"content":{"rendered":"<table style=\"width: 100%; border: none;\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" class=\"alignright\" style=\"text-align: right; width: 600px; border: none;\" src=\"\/wp-content\/uploads\/2026\/01\/2livres_Marie_Vingtras.jpg\" alt=\"Blizzard et Les \u00e2mes f\u00e9roces - Marie Vingtras\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\"><strong>Marie Vingtras<\/strong><br \/>\n<strong>BLIZZARD<\/strong><br \/>\n<strong>\u00c9diteur : <span class=\"a-list-item\"><span class=\"a-text-bold\">\u00c9ditions de l&rsquo;Olivier &#8211; ao\u00fbt 2021<\/span><\/span><\/strong><br \/>\n<strong>EAN : <span class=\"a-list-item\">978-2823617054<\/span><br \/>\n<\/strong><br \/>\n<strong>LES \u00c2MES F\u00c9ROCES<\/strong><br \/>\n<strong>\u00c9diteur : <span class=\"a-list-item\"><span class=\"a-text-bold\">\u00c9ditions de l&rsquo;Olivier &#8211; ao\u00fbt 2024<\/span><\/span><\/strong><br \/>\n<strong>EAN : <span class=\"a-list-item\">978-2823621020<\/span><br \/>\n<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\">Avocate sp\u00e9cialis\u00e9e dans le droit du travail Marie Vingtras est aussi devenue romanci\u00e8re.<\/p>\n<p>Elle a d\u00e9j\u00e0 rev\u00eatu l&rsquo;\u00e9toffe de la notori\u00e9t\u00e9 gr\u00e2ce \u00e0 la publication de ses deux premiers romans qui ont \u00e9t\u00e9 maintes fois prim\u00e9s.<\/p>\n<p>Sa profession lui a-t-elle permis d&rsquo;entrevoir, au-del\u00e0 des apparences, la complexit\u00e9 de la \u00ab\u00a0Nature\u00a0\u00bb humaine ?<br \/>\nElle parvient \u00e0 nous r\u00e9v\u00e9ler discr\u00e8tement sa pens\u00e9e sur un sujet que les philosophes ont tous plus ou moins explor\u00e9, sans obtenir de r\u00e9sultats v\u00e9ritablement probants puisque la \u00ab\u00a0Nature\u00a0\u00bb humaine s&rsquo;\u00e9vade et se reconstruit au cours des si\u00e8cles en fonction de l&rsquo;\u00e9volution de nos civilisations.<\/p>\n<p>Aussi c&rsquo;est avec une certaine sagesse que cette autrice semble s&rsquo;interdire tout jugement pour nous conter deux histoires \u00e9mouvantes dont les h\u00e9ros imagin\u00e9s paraissent se d\u00e9placer au sein de territoires \u00ab\u00a0en sable mouvant\u00a0\u00bb.<\/p>\n<p>\u00ab\u00a0Blizzard\u00a0\u00bb et \u00ab\u00a0les \u00e2mes f\u00e9roces\u00a0\u00bb ne sont pas des Thrillers bien que le suspens et la tension narrative qui sous-tendent ces deux \u00e9crits incitent le lecteur \u00e0 se h\u00e2ter pour conna\u00eetre le d\u00e9nouement de chacun des r\u00e9cits abord\u00e9s.<\/p>\n<p>Lire la prose de Marie Vingtras est  &#8211; \u00e0 mon avis  &#8211; surtout une invitation \u00e0 l&rsquo;introspection, car \u00e0 travers les personnages atypiques qui \u00e9voluent dans l&rsquo;immensit\u00e9 de l&rsquo;espace\/temps d&rsquo;une Am\u00e9rique polymorphe nous pouvons malgr\u00e9 les distances nous identifier \u00e0 ces \u00eatres fictifs mais \u00ab\u00a0humains\u00a0\u00bb et parfois \u00ab\u00a0inhumains\u00a0\u00bb qui sont ce que nous sommes et qui construisent le maillage des diff\u00e9rentes soci\u00e9t\u00e9s auxquelles nous appartenons.<\/p>\n<p>Ces deux \u0153uvres \u00e9labor\u00e9es selon des sch\u00e9mas narratifs tr\u00e8s diff\u00e9rents sont &#8211; paradoxalement &#8211; port\u00e9es par une structure rigoureuse offrant au lecteur des rep\u00e8res suffisamment pr\u00e9cis pour que ce dernier int\u00e8gre ais\u00e9ment le d\u00e9roulement des r\u00e9cits dont il est ici question.<\/p>\n<p>Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\/ou po\u00e9tiques.<\/p>\n<p>Les th\u00e8mes abord\u00e9s entrent en redondance avec les probl\u00e9matiques soci\u00e9tales et g\u00e9opolitiques des 20 et 21e si\u00e8cles,<br \/>\nintroduisant des personnages en recherche d&rsquo;un devenir meilleur quelles que soient les solutions adopt\u00e9es pour parvenir \u00e0 vivre ou \u00e0 survivre dans un univers qu&rsquo;ils ne parviennent pas v\u00e9ritablement \u00e0 habiter.<\/p>\n<p>\u00ab\u00a0Blizzard\u00a0\u00bb et \u00ab\u00a0Les \u00e2mes f\u00e9roces\u00a0\u00bb font partie de ces ouvrages dont l&rsquo;\u00e9criture en \u00ab\u00a0clair\/OBSCUR\u00a0\u00bb souligne la fragilit\u00e9 de la nature humaine et les d\u00e9viances qui peuvent survenir dans un monde o\u00f9 le sens des valeurs \u00e9thiques semble se d\u00e9liter insidieusement au fil du temps.<\/p>\n<p>Marie Vingtras va-t-elle poursuivre son travail de t\u00e9moin du temps qui passe \u00e0 travers des \u0153uvres fictives et ainsi r\u00e9pondre &#8211; de mani\u00e8re sous-jacente &#8211; \u00e0 d&rsquo;autres r\u00e9sonances pour fa\u00e7onner une note d&rsquo;esp\u00e9rance au seuil d&rsquo;une civilisation qui risquerait de se d\u00e9vitaliser par l&rsquo;apport exponentiel d&rsquo;un mod\u00e8le virtuel num\u00e9rique utile mais parfois d\u00e9shumanis\u00e9 ?<\/p>\n<p>J&rsquo;avoue &#8211; pour ma part &#8211; attendre avec impatience &#8211; l&rsquo;\u00e9mergence des  r\u00e9cits \u00e0 venir de Madame Marie Vingtras, autrice qui ne cessera peut-\u00eatre pas de nous \u00e9tonner ?<\/p>\n<p>Marie Vingtras n&rsquo;a \u00e9crit que deux romans, elle en \u00e9crira d&rsquo;autres&#8230; CELA&#8230;je puis vous l&rsquo;assurer ?!&#8230;.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">B\u00e9atrysse Dartstray<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Marie Vingtras BLIZZARD \u00c9diteur : \u00c9ditions de l&rsquo;Olivier &#8211; ao\u00fbt 2021 EAN : 978-2823617054 LES \u00c2MES F\u00c9ROCES \u00c9diteur : \u00c9ditions de l&rsquo;Olivier &#8211; ao\u00fbt 2024 EAN : 978-2823621020 Avocate sp\u00e9cialis\u00e9e dans le droit du travail Marie Vingtras est aussi devenue romanci\u00e8re. Elle a d\u00e9j\u00e0 rev\u00eatu l&rsquo;\u00e9toffe de la notori\u00e9t\u00e9 gr\u00e2ce \u00e0 la publication de ses &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;BLIZZARD et LES \u00c2MES F\u00c9ROCES &#8211; Marie Vingtras&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[1563,1555,1558,1557,1556,1562,1559,1560,1561,1564],"class_list":["post-1438","post","type-post","status-publish","format-standard","hentry","category-petite-bibliotheque","tag-amerique-polymorphe","tag-avocate-specialisee","tag-blizzard","tag-deux-premiers-romans","tag-droit-du-travail","tag-histoires-emouvantes","tag-les-ames-feroces","tag-marie-vingtras","tag-nature-humaine","tag-problematiques-societales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BLIZZARD et LES \u00c2MES F\u00c9ROCES - Marie Vingtras - B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste<\/title>\n<meta name=\"description\" content=\"Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\/ou po\u00e9tiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BLIZZARD et LES \u00c2MES F\u00c9ROCES - Marie Vingtras - B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste\" \/>\n<meta property=\"og:description\" content=\"Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\/ou po\u00e9tiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/\" \/>\n<meta property=\"og:site_name\" content=\"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T16:08:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T16:08:48+00:00\" \/>\n<meta name=\"author\" content=\"Beatrysse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatrysse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/\"},\"author\":{\"name\":\"Beatrysse\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#\\\/schema\\\/person\\\/6028c912862314c24da1ba7ca2a56a0a\"},\"headline\":\"BLIZZARD et LES \u00c2MES F\u00c9ROCES &#8211; Marie Vingtras\",\"datePublished\":\"2026-01-13T16:08:45+00:00\",\"dateModified\":\"2026-01-13T16:08:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/\"},\"wordCount\":594,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#organization\"},\"keywords\":[\"am\u00e9rique polymorphe\",\"avocate sp\u00e9cialis\u00e9e\",\"blizzard\",\"deux premiers romans\",\"droit du travail\",\"histoires \u00e9mouvantes\",\"les \u00e2mes f\u00e9roces\",\"marie vingtras\",\"nature humaine\",\"probl\u00e9matiques soci\u00e9tales\"],\"articleSection\":[\"Petite biblioth\u00e8que\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/\",\"url\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/\",\"name\":\"BLIZZARD et LES \u00c2MES F\u00c9ROCES - Marie Vingtras - B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#website\"},\"datePublished\":\"2026-01-13T16:08:45+00:00\",\"dateModified\":\"2026-01-13T16:08:48+00:00\",\"description\":\"Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\\\/ou po\u00e9tiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/2026\\\/01\\\/13\\\/blizzard-et-les-ames-feroces-marie-vingtras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BLIZZARD et LES \u00c2MES F\u00c9ROCES &#8211; Marie Vingtras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/\",\"name\":\"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste\",\"description\":\"Lecture plaisir...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#organization\",\"name\":\"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste\",\"url\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cropped-havre_ecrivaine-essayiste.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cropped-havre_ecrivaine-essayiste.jpg\",\"width\":2000,\"height\":1199,\"caption\":\"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/#\\\/schema\\\/person\\\/6028c912862314c24da1ba7ca2a56a0a\",\"name\":\"Beatrysse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/460d9453eec44e3f1b526a4d80f87d69ec5bbd5f3beeb2ea12472ef865b22572?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/460d9453eec44e3f1b526a4d80f87d69ec5bbd5f3beeb2ea12472ef865b22572?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/460d9453eec44e3f1b526a4d80f87d69ec5bbd5f3beeb2ea12472ef865b22572?s=96&d=identicon&r=g\",\"caption\":\"Beatrysse\"},\"url\":\"https:\\\/\\\/www.ecrivaine-essayiste.fr\\\/index.php\\\/author\\\/beatrysse\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BLIZZARD et LES \u00c2MES F\u00c9ROCES - Marie Vingtras - B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste","description":"Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\/ou po\u00e9tiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/","og_locale":"fr_FR","og_type":"article","og_title":"BLIZZARD et LES \u00c2MES F\u00c9ROCES - Marie Vingtras - B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste","og_description":"Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\/ou po\u00e9tiques.","og_url":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/","og_site_name":"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste","article_published_time":"2026-01-13T16:08:45+00:00","article_modified_time":"2026-01-13T16:08:48+00:00","author":"Beatrysse","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Beatrysse","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/#article","isPartOf":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/"},"author":{"name":"Beatrysse","@id":"https:\/\/www.ecrivaine-essayiste.fr\/#\/schema\/person\/6028c912862314c24da1ba7ca2a56a0a"},"headline":"BLIZZARD et LES \u00c2MES F\u00c9ROCES &#8211; Marie Vingtras","datePublished":"2026-01-13T16:08:45+00:00","dateModified":"2026-01-13T16:08:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/"},"wordCount":594,"publisher":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/#organization"},"keywords":["am\u00e9rique polymorphe","avocate sp\u00e9cialis\u00e9e","blizzard","deux premiers romans","droit du travail","histoires \u00e9mouvantes","les \u00e2mes f\u00e9roces","marie vingtras","nature humaine","probl\u00e9matiques soci\u00e9tales"],"articleSection":["Petite biblioth\u00e8que"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/","url":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/","name":"BLIZZARD et LES \u00c2MES F\u00c9ROCES - Marie Vingtras - B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste","isPartOf":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/#website"},"datePublished":"2026-01-13T16:08:45+00:00","dateModified":"2026-01-13T16:08:48+00:00","description":"Le style alerte sans fioritures inutiles donne \u00e0 entendre des sonorit\u00e9s \u00e0 la fois percutantes m\u00e9lancoliques et\/ou po\u00e9tiques.","breadcrumb":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/2026\/01\/13\/blizzard-et-les-ames-feroces-marie-vingtras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ecrivaine-essayiste.fr\/"},{"@type":"ListItem","position":2,"name":"BLIZZARD et LES \u00c2MES F\u00c9ROCES &#8211; Marie Vingtras"}]},{"@type":"WebSite","@id":"https:\/\/www.ecrivaine-essayiste.fr\/#website","url":"https:\/\/www.ecrivaine-essayiste.fr\/","name":"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste","description":"Lecture plaisir...","publisher":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecrivaine-essayiste.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ecrivaine-essayiste.fr\/#organization","name":"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste","url":"https:\/\/www.ecrivaine-essayiste.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ecrivaine-essayiste.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ecrivaine-essayiste.fr\/wp-content\/uploads\/2017\/08\/cropped-havre_ecrivaine-essayiste.jpg","contentUrl":"https:\/\/www.ecrivaine-essayiste.fr\/wp-content\/uploads\/2017\/08\/cropped-havre_ecrivaine-essayiste.jpg","width":2000,"height":1199,"caption":"B\u00e9atrysse Dartstray - \u00c9crivaine-essayiste"},"image":{"@id":"https:\/\/www.ecrivaine-essayiste.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ecrivaine-essayiste.fr\/#\/schema\/person\/6028c912862314c24da1ba7ca2a56a0a","name":"Beatrysse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/460d9453eec44e3f1b526a4d80f87d69ec5bbd5f3beeb2ea12472ef865b22572?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/460d9453eec44e3f1b526a4d80f87d69ec5bbd5f3beeb2ea12472ef865b22572?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/460d9453eec44e3f1b526a4d80f87d69ec5bbd5f3beeb2ea12472ef865b22572?s=96&d=identicon&r=g","caption":"Beatrysse"},"url":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/author\/beatrysse\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/posts\/1438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1438"}],"version-history":[{"count":2,"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/posts\/1438\/revisions"}],"predecessor-version":[{"id":1441,"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/posts\/1438\/revisions\/1441"}],"wp:attachment":[{"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecrivaine-essayiste.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}